{"id":11839,"date":"2026-07-15T14:28:37","date_gmt":"2026-07-15T14:28:37","guid":{"rendered":"https:\/\/test.elessentct.com\/?p=11839"},"modified":"2026-07-15T14:55:36","modified_gmt":"2026-07-15T14:55:36","slug":"totalenergies-achieves-emission-reduction-goals-as-belco-gas-cleaning-technology-goes-live-in-antwerp","status":"publish","type":"post","link":"https:\/\/test.elessentct.com\/zh\/totalenergies-achieves-emission-reduction-goals-as-belco-gas-cleaning-technology-goes-live-in-antwerp\/","title":{"rendered":"\u968f\u7740BELCO\u00ae\u6c14\u4f53\u51c0\u5316\u6280\u672f\u5728\u5b89\u7279\u536b\u666e\u6295\u5165\u8fd0\u884c\uff0c\u9053\u8fbe\u5c14\u80fd\u6e90\u5b9e\u73b0\u4e86\u51cf\u6392\u76ee\u6807"},"content":{"rendered":"<p>Elessent Clean Technologies\uff08Elessent\uff09\u6b23\u7136\u5ba3\u5e03\uff0c\u5176BELCO\u00ae\u96c6\u6210\u6c14\u4f53\u51c0\u5316\u7cfb\u7edf\u5df2\u5728\u6bd4\u5229\u65f6\u5b89\u7279\u536b\u666e\u7684\u9053\u8fbe\u5c14\u80fd\u6e90\uff08TotalEnergies\uff09\u70bc\u6cb9\u5382\u6210\u529f\u6295\u4ea7\u3002.\u00a0<\/p>\n\n\n\n<p><a class=\"wp-block-file__button wp-element-button button\" href=\"\/wp-content\/uploads\/2026\/07\/2026-07-14-BELCO-Scrubber-at-TotalEnergies-Press-Release_Final.pdf\" target=\"_blank\" rel=\"noopener\" download=\"\" aria-describedby=\"wp-block-file--media-15b2b3f9-9f49-4e4e-94ce-01d2cbb5f3fc\">\u4e0b\u8f7d<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Elessent Clean Technologies\uff08Elessent\uff09\u6b23\u7136\u5ba3\u5e03\uff0c\u5176BELCO\u00ae\u96c6\u6210\u6c14\u4f53\u51c0\u5316\u7cfb\u7edf\u5df2\u5728\u6bd4\u5229\u65f6\u5b89\u7279\u536b\u666e\u7684\u9053\u8fbe\u5c14\u80fd\u6e90\uff08TotalEnergies\uff09\u70bc\u6cb9\u5382\u6210\u529f\u6295\u4ea7\u3002.\u00a0<\/p>","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"brochure_require_email":false,"footnotes":""},"categories":[9],"tags":[60,48,121],"class_list":["post-11839","post","type-post","status-publish","format-standard","hentry","category-news","tag-air-pollution-control","tag-belco","tag-flue-gas-cleaning"],"_links":{"self":[{"href":"https:\/\/test.elessentct.com\/zh\/wp-json\/wp\/v2\/posts\/11839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.elessentct.com\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/test.elessentct.com\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/test.elessentct.com\/zh\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/test.elessentct.com\/zh\/wp-json\/wp\/v2\/comments?post=11839"}],"version-history":[{"count":2,"href":"https:\/\/test.elessentct.com\/zh\/wp-json\/wp\/v2\/posts\/11839\/revisions"}],"predecessor-version":[{"id":11841,"href":"https:\/\/test.elessentct.com\/zh\/wp-json\/wp\/v2\/posts\/11839\/revisions\/11841"}],"wp:attachment":[{"href":"https:\/\/test.elessentct.com\/zh\/wp-json\/wp\/v2\/media?parent=11839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/test.elessentct.com\/zh\/wp-json\/wp\/v2\/categories?post=11839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/test.elessentct.com\/zh\/wp-json\/wp\/v2\/tags?post=11839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}