{"id":11804,"date":"2026-06-04T21:54:44","date_gmt":"2026-06-04T21:54:44","guid":{"rendered":"https:\/\/elessentct.com\/?p=11804"},"modified":"2026-06-04T21:54:49","modified_gmt":"2026-06-04T21:54:49","slug":"elessent-clean-technologies-forms-strategic-alliance-with-thermal-systems-pvt-ltd","status":"publish","type":"post","link":"https:\/\/test.elessentct.com\/zh\/elessent-clean-technologies-forms-strategic-alliance-with-thermal-systems-pvt-ltd\/","title":{"rendered":"Elessent Clean Technologies \u4e0e Thermal Systems Pvt Ltd \u5efa\u7acb\u6218\u7565\u8054\u76df"},"content":{"rendered":"<p>Elessent Clean Technologies\uff08Elessent\uff09\u6b23\u7136\u5ba3\u5e03\uff0c\u5df2\u4e0e\u603b\u90e8\u4f4d\u4e8e\u5370\u5ea6\u6d77\u5f97\u62c9\u5df4\u7684\u9886\u5148\u84b8\u6c7d\u8bbe\u5907\u4f9b\u5e94\u5546Thermal Systems Private Limited\uff08Thermal Systems\uff09\u7b7e\u7f72\u4e86\u6218\u7565\u8054\u76df\u534f\u8bae\u3002 \u8be5\u534f\u8bae\u5c06Elessent\u903e\u767e\u5e74\u7684MECS\u00ae\u786b\u9178\u5382\u4e13\u4e1a\u6280\u672f\u4e0eThermal Systems\u56db\u5341\u4f59\u5e74\u7684\u84b8\u6c7d\u8bbe\u5907\u7ecf\u9a8c\u76f8\u7ed3\u5408\uff0c\u65e8\u5728\u4e3a\u5ba2\u6237\u63d0\u4f9b\u9ad8\u6548\u89e3\u51b3\u65b9\u6848\u3002.<\/p>\n\n\n\n<p><a class=\"wp-block-file__button wp-element-button button\" href=\"\/wp-content\/uploads\/2026\/06\/2026-4-28_-MECS-Alliance-Agreement-with-Thermal-Systems-Private-Limited-Press-Release-FINAL.pdf\" target=\"_blank\" rel=\"noopener\" download=\"\" aria-describedby=\"wp-block-file--media-15b2b3f9-9f49-4e4e-94ce-01d2cbb5f3fc\">\u4e0b\u8f7d<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Elessent Clean Technologies\uff08\u4ee5\u4e0b\u7b80\u79f0\u201cElessent\u201d\uff09\u6b23\u7136\u5ba3\u5e03\uff0c\u5df2\u4e0e\u603b\u90e8\u4f4d\u4e8e\u5370\u5ea6\u6d77\u5f97\u62c9\u5df4\u7684\u9886\u5148\u84b8\u6c7d\u8bbe\u5907\u4f9b\u5e94\u5546Thermal Systems Private Limited\uff08\u4ee5\u4e0b\u7b80\u79f0\u201cThermal Systems\u201d\uff09\u7b7e\u7f72\u6218\u7565\u8054\u76df\u534f\u8bae\u3002\u8be5\u534f\u8bae\u878d\u5408\u4e86MECS\u00ae\u903e\u767e\u5e74\u7684\u2026\u2026<\/p>","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"brochure_require_email":false,"footnotes":""},"categories":[9],"tags":[99,46],"class_list":["post-11804","post","type-post","status-publish","format-standard","hentry","category-news","tag-equipment","tag-mecs"],"_links":{"self":[{"href":"https:\/\/test.elessentct.com\/zh\/wp-json\/wp\/v2\/posts\/11804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.elessentct.com\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/test.elessentct.com\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/test.elessentct.com\/zh\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/test.elessentct.com\/zh\/wp-json\/wp\/v2\/comments?post=11804"}],"version-history":[{"count":1,"href":"https:\/\/test.elessentct.com\/zh\/wp-json\/wp\/v2\/posts\/11804\/revisions"}],"predecessor-version":[{"id":11805,"href":"https:\/\/test.elessentct.com\/zh\/wp-json\/wp\/v2\/posts\/11804\/revisions\/11805"}],"wp:attachment":[{"href":"https:\/\/test.elessentct.com\/zh\/wp-json\/wp\/v2\/media?parent=11804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/test.elessentct.com\/zh\/wp-json\/wp\/v2\/categories?post=11804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/test.elessentct.com\/zh\/wp-json\/wp\/v2\/tags?post=11804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}